{"id":5091,"date":"2020-09-07T10:15:52","date_gmt":"2020-09-07T10:15:52","guid":{"rendered":"https:\/\/staging.5starpropertiesaltea.com\/?p=5091"},"modified":"2020-10-06T09:15:48","modified_gmt":"2020-10-06T09:15:48","slug":"welcome-to-our-new-site","status":"publish","type":"post","link":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/","title":{"rendered":"Welcome to our new site!"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Welcome to the 5 Star Properties Altea website. We hope you like it! Please take a look around.<\/p>\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Welcome to the 5 Star Properties Altea website. We hope you like it! Please take a look around. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":5092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-5091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Welcome to our new site! - 5 Star Properties Altea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welcome to our new site! - 5 Star Properties Altea\" \/>\n<meta property=\"og:description\" content=\"Welcome to the 5 Star Properties Altea website. We hope you like it! Please take a look around. &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/\" \/>\n<meta property=\"og:site_name\" content=\"5 Star Properties Altea\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-07T10:15:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-06T09:15:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/5starpropertiesaltea.com\/wp-content\/uploads\/2020\/09\/Schermafbeelding-2020-09-07-om-12.13.54.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1904\" \/>\n\t<meta property=\"og:image:height\" content=\"863\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#\\\/schema\\\/person\\\/c576cf7a9ea786b1b9ac8b4471d51783\"},\"headline\":\"Welcome to our new site!\",\"datePublished\":\"2020-09-07T10:15:52+00:00\",\"dateModified\":\"2020-10-06T09:15:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/\"},\"wordCount\":23,\"publisher\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Schermafbeelding-2020-09-07-om-12.13.54.png\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/\",\"url\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/\",\"name\":\"Welcome to our new site! - 5 Star Properties Altea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Schermafbeelding-2020-09-07-om-12.13.54.png\",\"datePublished\":\"2020-09-07T10:15:52+00:00\",\"dateModified\":\"2020-10-06T09:15:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/#primaryimage\",\"url\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Schermafbeelding-2020-09-07-om-12.13.54.png\",\"contentUrl\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Schermafbeelding-2020-09-07-om-12.13.54.png\",\"width\":1904,\"height\":863},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/welcome-to-our-new-site\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Welcome to our new site!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/\",\"name\":\"5 Star Properties Altea\",\"description\":\"Buy real estate in the Altea region\",\"publisher\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#organization\",\"name\":\"5 Star Properties Altea\",\"url\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-5starpropertiesaltea-zwart.png\",\"contentUrl\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-5starpropertiesaltea-zwart.png\",\"width\":8623,\"height\":1064,\"caption\":\"5 Star Properties Altea\"},\"image\":{\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/#\\\/schema\\\/person\\\/c576cf7a9ea786b1b9ac8b4471d51783\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/462438ea1f90caf7e8ed595523135dd8f9211f35b26cc77ab744f9059dc620d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/462438ea1f90caf7e8ed595523135dd8f9211f35b26cc77ab744f9059dc620d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/462438ea1f90caf7e8ed595523135dd8f9211f35b26cc77ab744f9059dc620d9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/5starpropertiesaltea.com\"],\"url\":\"https:\\\/\\\/5starpropertiesaltea.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Welcome to our new site! - 5 Star Properties Altea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/","og_locale":"en_US","og_type":"article","og_title":"Welcome to our new site! - 5 Star Properties Altea","og_description":"Welcome to the 5 Star Properties Altea website. We hope you like it! Please take a look around. &nbsp;","og_url":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/","og_site_name":"5 Star Properties Altea","article_published_time":"2020-09-07T10:15:52+00:00","article_modified_time":"2020-10-06T09:15:48+00:00","og_image":[{"width":1904,"height":863,"url":"https:\/\/5starpropertiesaltea.com\/wp-content\/uploads\/2020\/09\/Schermafbeelding-2020-09-07-om-12.13.54.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/#article","isPartOf":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/"},"author":{"name":"admin","@id":"https:\/\/5starpropertiesaltea.com\/en\/#\/schema\/person\/c576cf7a9ea786b1b9ac8b4471d51783"},"headline":"Welcome to our new site!","datePublished":"2020-09-07T10:15:52+00:00","dateModified":"2020-10-06T09:15:48+00:00","mainEntityOfPage":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/"},"wordCount":23,"publisher":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/#organization"},"image":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/#primaryimage"},"thumbnailUrl":"https:\/\/5starpropertiesaltea.com\/wp-content\/uploads\/2020\/09\/Schermafbeelding-2020-09-07-om-12.13.54.png","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/","url":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/","name":"Welcome to our new site! - 5 Star Properties Altea","isPartOf":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/#primaryimage"},"image":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/#primaryimage"},"thumbnailUrl":"https:\/\/5starpropertiesaltea.com\/wp-content\/uploads\/2020\/09\/Schermafbeelding-2020-09-07-om-12.13.54.png","datePublished":"2020-09-07T10:15:52+00:00","dateModified":"2020-10-06T09:15:48+00:00","breadcrumb":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/#primaryimage","url":"https:\/\/5starpropertiesaltea.com\/wp-content\/uploads\/2020\/09\/Schermafbeelding-2020-09-07-om-12.13.54.png","contentUrl":"https:\/\/5starpropertiesaltea.com\/wp-content\/uploads\/2020\/09\/Schermafbeelding-2020-09-07-om-12.13.54.png","width":1904,"height":863},{"@type":"BreadcrumbList","@id":"https:\/\/5starpropertiesaltea.com\/en\/welcome-to-our-new-site\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/5starpropertiesaltea.com\/en\/"},{"@type":"ListItem","position":2,"name":"Welcome to our new site!"}]},{"@type":"WebSite","@id":"https:\/\/5starpropertiesaltea.com\/en\/#website","url":"https:\/\/5starpropertiesaltea.com\/en\/","name":"5 Star Properties Altea","description":"Buy real estate in the Altea region","publisher":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/5starpropertiesaltea.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/5starpropertiesaltea.com\/en\/#organization","name":"5 Star Properties Altea","url":"https:\/\/5starpropertiesaltea.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/5starpropertiesaltea.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/5starpropertiesaltea.com\/wp-content\/uploads\/2020\/10\/logo-5starpropertiesaltea-zwart.png","contentUrl":"https:\/\/5starpropertiesaltea.com\/wp-content\/uploads\/2020\/10\/logo-5starpropertiesaltea-zwart.png","width":8623,"height":1064,"caption":"5 Star Properties Altea"},"image":{"@id":"https:\/\/5starpropertiesaltea.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/5starpropertiesaltea.com\/en\/#\/schema\/person\/c576cf7a9ea786b1b9ac8b4471d51783","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/462438ea1f90caf7e8ed595523135dd8f9211f35b26cc77ab744f9059dc620d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/462438ea1f90caf7e8ed595523135dd8f9211f35b26cc77ab744f9059dc620d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462438ea1f90caf7e8ed595523135dd8f9211f35b26cc77ab744f9059dc620d9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/5starpropertiesaltea.com"],"url":"https:\/\/5starpropertiesaltea.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/posts\/5091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/comments?post=5091"}],"version-history":[{"count":3,"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/posts\/5091\/revisions"}],"predecessor-version":[{"id":5737,"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/posts\/5091\/revisions\/5737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/media\/5092"}],"wp:attachment":[{"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/media?parent=5091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/categories?post=5091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/5starpropertiesaltea.com\/en\/wp-json\/wp\/v2\/tags?post=5091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}